﻿{"id":132584,"date":"2019-10-24T22:24:08","date_gmt":"2019-10-24T20:24:08","guid":{"rendered":"https:\/\/paladarplus.es\/acappela-roble\/"},"modified":"2025-12-12T10:01:05","modified_gmt":"2025-12-12T08:01:05","slug":"acappela-roble","status":"publish","type":"product","link":"https:\/\/paladarplus.es\/en\/acappela-roble\/","title":{"rendered":"Acappela Roble 2024"},"content":{"rendered":"<p>Acappela Roble tiene su origen en los vi\u00f1edos m\u00e1s frescos situados cerca del r\u00edo Duero. El suelo es franco-arenoso con ligero contenido de cascajo. Esto le aporta una frescura muy caracter\u00edstica que combinada con su paso por barrica da lugar a un vino con gran personalidad y con marcados matices afrutados.<\/p>\n<p>Elaborado a partir de uva 100% Tempranillo, posee una crianza de 5 meses en barricas de roble franc\u00e9s (50%) y americano (50%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vino Ribera del Duero con 5 meses de crianza en roble<\/p>\n","protected":false},"featured_media":46534,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14631,14023,14678,14109,14017,13993],"product_tag":[],"class_list":["post-132584","product","type-product","status-publish","has-post-thumbnail","product_cat-ribera-del-duero-joven-en","product_cat-uva-tempranillo-en","product_cat-jovenes-en","product_cat-vino-ribera-del-duero-en","product_cat-vino-tinto-en","product_cat-vinos-en","pa_anada-2024-en","pa_denomination_of_origin-52-riberadelduero-en","pa_formato_de_botella-20-75cl-en","pa_googleshopping_exclude-83-1-en","pa_graduacion_alcoholica-bc-13_5degraduacionalcoholica-en","pa_grape_variety-18-tempranillo-en","pa_grape_variety-15-tintadelpais-en","pa_occasion-9f-aperitivos-en","pa_occasion-69-cenainformal-en","pa_pairing-9f-aperitivos-en","pa_pairing-42-arroces-en","pa_pairing-11-carnesblancas-en","pa_pairing-99-carnesrojas-en","pa_product_label_background_colo-86-ff0000-en","pa_product_label_color-6e-ffffff-en","pa_product_label_select-7f-none-en","pa_style-58-roble-en","pa_wine_type-99-tinto-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Cappela Roble Vino Tinto d.o. Ribera del Duero para Comprar Online<\/title>\n<meta name=\"description\" content=\"A Cappela Roble es un Vino Tinto de Bodegas Monteabell\u00f3n con denominaci\u00f3n de origen Ribera del Duero y una crianza de 5 meses en barrica de roble, elaborado a partir de la variedad de uva 100% tempranillo que puedes comprar online al mejor precio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paladarplus.es\/en\/acappela-roble\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Cappela Roble Vino Tinto d.o. Ribera del Duero para Comprar Online\" \/>\n<meta property=\"og:description\" content=\"A Cappela Roble es un Vino Tinto de Bodegas Monteabell\u00f3n con denominaci\u00f3n de origen Ribera del Duero y una crianza de 5 meses en barrica de roble, elaborado a partir de la variedad de uva 100% tempranillo que puedes comprar online al mejor precio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paladarplus.es\/en\/acappela-roble\/\" \/>\n<meta property=\"og:site_name\" content=\"Paladar Plus\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T08:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paladarplus.es\/wp-content\/uploads\/2019\/10\/acappela_roble-compressor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"198\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/\",\"name\":\"A Cappela Roble Vino Tinto d.o. Ribera del Duero para Comprar Online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/acappela_roble-compressor.jpg\",\"datePublished\":\"2019-10-24T20:24:08+00:00\",\"dateModified\":\"2025-12-12T08:01:05+00:00\",\"description\":\"A Cappela Roble es un Vino Tinto de Bodegas Monteabell\u00f3n con denominaci\u00f3n de origen Ribera del Duero y una crianza de 5 meses en barrica de roble, elaborado a partir de la variedad de uva 100% tempranillo que puedes comprar online al mejor precio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/acappela_roble-compressor.jpg\",\"contentUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/acappela_roble-compressor.jpg\",\"width\":198,\"height\":699},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/acappela-roble\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Acappela Roble 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\",\"name\":\"Paladar Plus\",\"description\":\"Tienda de Vinos Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Cappela Roble Vino Tinto d.o. Ribera del Duero para Comprar Online","description":"A Cappela Roble es un Vino Tinto de Bodegas Monteabell\u00f3n con denominaci\u00f3n de origen Ribera del Duero y una crianza de 5 meses en barrica de roble, elaborado a partir de la variedad de uva 100% tempranillo que puedes comprar online al mejor precio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paladarplus.es\/en\/acappela-roble\/","og_locale":"en_US","og_type":"article","og_title":"A Cappela Roble Vino Tinto d.o. Ribera del Duero para Comprar Online","og_description":"A Cappela Roble es un Vino Tinto de Bodegas Monteabell\u00f3n con denominaci\u00f3n de origen Ribera del Duero y una crianza de 5 meses en barrica de roble, elaborado a partir de la variedad de uva 100% tempranillo que puedes comprar online al mejor precio","og_url":"https:\/\/paladarplus.es\/en\/acappela-roble\/","og_site_name":"Paladar Plus","article_modified_time":"2025-12-12T08:01:05+00:00","og_image":[{"width":198,"height":699,"url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2019\/10\/acappela_roble-compressor.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paladarplus.es\/en\/acappela-roble\/","url":"https:\/\/paladarplus.es\/en\/acappela-roble\/","name":"A Cappela Roble Vino Tinto d.o. Ribera del Duero para Comprar Online","isPartOf":{"@id":"https:\/\/paladarplus.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paladarplus.es\/en\/acappela-roble\/#primaryimage"},"image":{"@id":"https:\/\/paladarplus.es\/en\/acappela-roble\/#primaryimage"},"thumbnailUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2019\/10\/acappela_roble-compressor.jpg","datePublished":"2019-10-24T20:24:08+00:00","dateModified":"2025-12-12T08:01:05+00:00","description":"A Cappela Roble es un Vino Tinto de Bodegas Monteabell\u00f3n con denominaci\u00f3n de origen Ribera del Duero y una crianza de 5 meses en barrica de roble, elaborado a partir de la variedad de uva 100% tempranillo que puedes comprar online al mejor precio","breadcrumb":{"@id":"https:\/\/paladarplus.es\/en\/acappela-roble\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paladarplus.es\/en\/acappela-roble\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paladarplus.es\/en\/acappela-roble\/#primaryimage","url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2019\/10\/acappela_roble-compressor.jpg","contentUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2019\/10\/acappela_roble-compressor.jpg","width":198,"height":699},{"@type":"BreadcrumbList","@id":"https:\/\/paladarplus.es\/en\/acappela-roble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paladarplus.es\/en\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/paladarplus.es\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Acappela Roble 2024"}]},{"@type":"WebSite","@id":"https:\/\/paladarplus.es\/es\/#website","url":"https:\/\/paladarplus.es\/es\/","name":"Paladar Plus","description":"Tienda de Vinos Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paladarplus.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product\/132584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/comments?post=132584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/media\/46534"}],"wp:attachment":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/media?parent=132584"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product_brand?post=132584"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product_cat?post=132584"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product_tag?post=132584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}