﻿{"id":19776,"count":1,"description":"","link":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/","name":"La Rinconada Blanco","slug":"la-rinconada-blanco-en","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Rinconada Blanco Archives - Paladar Plus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Rinconada Blanco Archives - Paladar Plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Paladar Plus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/la-rinconada-blanco-en\\\/\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/la-rinconada-blanco-en\\\/\",\"name\":\"La Rinconada Blanco Archives - Paladar Plus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/la-rinconada-blanco-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/la-rinconada-blanco-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Rinconada Blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\",\"name\":\"Paladar Plus\",\"description\":\"Tienda de Vinos Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Rinconada Blanco Archives - Paladar Plus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/","og_locale":"en_US","og_type":"article","og_title":"La Rinconada Blanco Archives - Paladar Plus","og_url":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/","og_site_name":"Paladar Plus","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/","url":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/","name":"La Rinconada Blanco Archives - Paladar Plus","isPartOf":{"@id":"https:\/\/paladarplus.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/paladarplus.es\/en\/la-rinconada-blanco-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paladarplus.es\/en\/"},{"@type":"ListItem","position":2,"name":"La Rinconada Blanco"}]},{"@type":"WebSite","@id":"https:\/\/paladarplus.es\/es\/#website","url":"https:\/\/paladarplus.es\/es\/","name":"Paladar Plus","description":"Tienda de Vinos Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paladarplus.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product_cat\/19776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/paladarplus.es\/en\/wp-json\/wp\/v2\/product?product_cat=19776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}