﻿{"id":27217,"date":"2016-04-06T10:06:52","date_gmt":"2016-04-06T08:06:52","guid":{"rendered":"https:\/\/paladarplus.es\/product\/vino-blanco-barco-del-corneta-verdejo\/"},"modified":"2022-12-23T14:16:44","modified_gmt":"2022-12-23T12:16:44","slug":"vino-blanco-barco-del-corneta-verdejo","status":"publish","type":"product","link":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/","title":{"rendered":"Vino Blanco Barco del Corneta Verdejo"},"content":{"rendered":"<p><strong>Barco del Corneta Verdejo<\/strong> es un Vino Blanco elaborado a partir de uva Verdejo vendimiada en su totalidad a mano. Los vi&ntilde;edos est&aacute;n situados en La Seca, en plena regi&oacute;n de Rueda, pero los vinos est&aacute;n amparados por la denominaci&oacute;n de origen Vinos de la Tierra de Castilla y Le&oacute;n.<\/p>\n<p>El vino tiene una crianza sobre sus l&iacute;as de 8 meses en barricas de roble franc&eacute;s de 300 litros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vino Blanco con una crianza sobre sus l\u00edas de 8 meses<\/p>\n","protected":false},"featured_media":27211,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2478,1093,1518,13713,983],"product_tag":[4052,4053],"class_list":["post-27217","product","type-product","status-publish","has-post-thumbnail","product_cat-con-barrica","product_cat-blancos","product_cat-vino-de-la-tierra-de-castilla-y-leon","product_cat-vino-de-la-tierra-de-castilla-y-leon-blanco","product_cat-vinos","product_tag-vino-blanco-barco-del-corneta","product_tag-vinos-verdejo","pa_anada-26-2013","pa_denomination_of_origin-f5-vinodelatierradecastillayl","pa_formato_de_botella-2d-0_75litros","pa_graduacion_alcoholica-9d-13degraduacionalcoholica","pa_grape_variety-be-verdejo","pa_manufacturer-c7-barcodelcorneta","pa_occasion-9f-aperitivos","pa_occasion-89-celebraciones","pa_occasion-69-cenainformal","pa_occasion-21-cenaromantica","pa_occasion-8e-comidaenfamilia","pa_occasion-b8-compromiso","pa_pairing-9f-aperitivos","pa_pairing-42-arroces","pa_pairing-11-carnesblancas","pa_pairing-8c-ensaladas","pa_pairing-7b-marisco","pa_pairing-5a-pasta","pa_pairing-5d-pescados","pa_style-98-blancoafrutado","pa_wine_type-fd-blanco","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprar Vino Blanco Barco del Corneta online | Vinos Verdejo<\/title>\n<meta name=\"description\" content=\"\u00bfDeseas comprar Barco del Corneta Verdejo online? En nuestra bodega online podr\u00e1s comprar Barco del Corneta Verdejo al mejor precio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprar Vino Blanco Barco del Corneta online | Vinos Verdejo\" \/>\n<meta property=\"og:description\" content=\"\u00bfDeseas comprar Barco del Corneta Verdejo online? En nuestra bodega online podr\u00e1s comprar Barco del Corneta Verdejo al mejor precio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/\" \/>\n<meta property=\"og:site_name\" content=\"Paladar Plus\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-23T12:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/barco_del_corneta_verdejo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"145\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/\",\"name\":\"Comprar Vino Blanco Barco del Corneta online | Vinos Verdejo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/barco_del_corneta_verdejo.jpg\",\"datePublished\":\"2016-04-06T08:06:52+00:00\",\"dateModified\":\"2022-12-23T12:16:44+00:00\",\"description\":\"\u00bfDeseas comprar Barco del Corneta Verdejo online? En nuestra bodega online podr\u00e1s comprar Barco del Corneta Verdejo al mejor precio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/barco_del_corneta_verdejo.jpg\",\"contentUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/barco_del_corneta_verdejo.jpg\",\"width\":145,\"height\":515,\"caption\":\"Vino Blanco Barco del Corneta Verdejo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-blanco-barco-del-corneta-verdejo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vino Blanco Barco del Corneta Verdejo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\",\"name\":\"Paladar Plus\",\"description\":\"Tienda de Vinos Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprar Vino Blanco Barco del Corneta online | Vinos Verdejo","description":"\u00bfDeseas comprar Barco del Corneta Verdejo online? En nuestra bodega online podr\u00e1s comprar Barco del Corneta Verdejo al mejor precio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/","og_locale":"es_ES","og_type":"article","og_title":"Comprar Vino Blanco Barco del Corneta online | Vinos Verdejo","og_description":"\u00bfDeseas comprar Barco del Corneta Verdejo online? En nuestra bodega online podr\u00e1s comprar Barco del Corneta Verdejo al mejor precio.","og_url":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/","og_site_name":"Paladar Plus","article_modified_time":"2022-12-23T12:16:44+00:00","og_image":[{"width":145,"height":515,"url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/barco_del_corneta_verdejo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/","url":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/","name":"Comprar Vino Blanco Barco del Corneta online | Vinos Verdejo","isPartOf":{"@id":"https:\/\/paladarplus.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/#primaryimage"},"image":{"@id":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/#primaryimage"},"thumbnailUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/barco_del_corneta_verdejo.jpg","datePublished":"2016-04-06T08:06:52+00:00","dateModified":"2022-12-23T12:16:44+00:00","description":"\u00bfDeseas comprar Barco del Corneta Verdejo online? En nuestra bodega online podr\u00e1s comprar Barco del Corneta Verdejo al mejor precio.","breadcrumb":{"@id":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/#primaryimage","url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/barco_del_corneta_verdejo.jpg","contentUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/barco_del_corneta_verdejo.jpg","width":145,"height":515,"caption":"Vino Blanco Barco del Corneta Verdejo"},{"@type":"BreadcrumbList","@id":"https:\/\/paladarplus.es\/es\/vino-blanco-barco-del-corneta-verdejo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paladarplus.es\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/paladarplus.es\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Vino Blanco Barco del Corneta Verdejo"}]},{"@type":"WebSite","@id":"https:\/\/paladarplus.es\/es\/#website","url":"https:\/\/paladarplus.es\/es\/","name":"Paladar Plus","description":"Tienda de Vinos Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paladarplus.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product\/27217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/comments?post=27217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/media\/27211"}],"wp:attachment":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/media?parent=27217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product_brand?post=27217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product_cat?post=27217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product_tag?post=27217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}