﻿{"id":27391,"date":"2016-04-25T09:55:54","date_gmt":"2016-04-25T07:55:54","guid":{"rendered":"https:\/\/paladarplus.es\/product\/vino-tinto-liberalia-dos\/"},"modified":"2023-07-01T21:41:08","modified_gmt":"2023-07-01T19:41:08","slug":"vino-tinto-liberalia-dos","status":"publish","type":"product","link":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/","title":{"rendered":"Liberalia Vino Dos Tinto 2020"},"content":{"rendered":"<p><strong>Liberalia Dos<\/strong> es un Vino de Toro elaborado a partir de <strong>uva Tinta de Toro<\/strong> (adaptaci\u00f3n de la Tempranillo a la zona) con una maduraci\u00f3n en barrica de tres meses. El m\u00e1s joven de la <strong>Bodega Liberalia<\/strong> Enol\u00f3gica.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/i-nOK5V8Ui4\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vino de Toro m\u00e1s joven de Bodega Liberalia<\/p>\n","protected":false},"featured_media":27385,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1723,13841,1013,1068,13681,1163,1203,2473,1058,983],"product_tag":[4065,4063,3598,4072,4061,3101,4064,4062],"class_list":["post-27391","product","type-product","status-publish","has-post-thumbnail","product_cat-liberalia-enologica","product_cat-liberalia-tinto","product_cat-ofertas","product_cat-outlet","product_cat-toro-tintos","product_cat-uva-tempranillo","product_cat-vino-de-toro","product_cat-jovenes","product_cat-vino-tinto","product_cat-vinos","product_tag-bodegas-liberalia","product_tag-toro-vino","product_tag-vino-de-toro","product_tag-vino-tinto-liberalia-dos","product_tag-vino-toro","product_tag-vinos-de-toro","product_tag-vinos-de-toro-zamora","product_tag-vinos-toro","pa_denomination_of_origin-e6-toro","pa_formato_de_botella-2d-0_75litros","pa_graduacion_alcoholica-94-14_5degraduacionalcoholica","pa_grape_variety-18-tempranillo","pa_manufacturer-9a-liberalia","pa_occasion-9f-aperitivos","pa_occasion-97-barbacoa","pa_occasion-69-cenainformal","pa_occasion-8e-comidaenfamilia","pa_pairing-9f-aperitivos","pa_pairing-99-carnesrojas","pa_pairing-a9-guisos","pa_style-55-joven","pa_wine_type-99-tinto","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liberalia Vino Dos Tinto d.o. Toro para Comprar online<\/title>\n<meta name=\"description\" content=\"Liberalia Vino Dos Tinto con denominaci\u00f3n de origen Vino de Toro es el m\u00e1s joven de Bodega Liberalia elaborado a partir de uva Tinta de Toro con una maduraci\u00f3n en barrica de tres meses que puedes comprar online y recibirlo en 48 horas en Paladar Plus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liberalia Vino Dos Tinto d.o. Toro para Comprar online\" \/>\n<meta property=\"og:description\" content=\"Liberalia Vino Dos Tinto con denominaci\u00f3n de origen Vino de Toro es el m\u00e1s joven de Bodega Liberalia elaborado a partir de uva Tinta de Toro con una maduraci\u00f3n en barrica de tres meses que puedes comprar online y recibirlo en 48 horas en Paladar Plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/\" \/>\n<meta property=\"og:site_name\" content=\"Paladar Plus\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-01T19:41:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/liberalia_dos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"135\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/\",\"name\":\"Liberalia Vino Dos Tinto d.o. Toro para Comprar online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/liberalia_dos.jpg\",\"datePublished\":\"2016-04-25T07:55:54+00:00\",\"dateModified\":\"2023-07-01T19:41:08+00:00\",\"description\":\"Liberalia Vino Dos Tinto con denominaci\u00f3n de origen Vino de Toro es el m\u00e1s joven de Bodega Liberalia elaborado a partir de uva Tinta de Toro con una maduraci\u00f3n en barrica de tres meses que puedes comprar online y recibirlo en 48 horas en Paladar Plus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/liberalia_dos.jpg\",\"contentUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/liberalia_dos.jpg\",\"width\":135,\"height\":528,\"caption\":\"Vino de Toro Liberalia Dos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/vino-tinto-liberalia-dos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Liberalia Vino Dos Tinto 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\",\"name\":\"Paladar Plus\",\"description\":\"Tienda de Vinos Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liberalia Vino Dos Tinto d.o. Toro para Comprar online","description":"Liberalia Vino Dos Tinto con denominaci\u00f3n de origen Vino de Toro es el m\u00e1s joven de Bodega Liberalia elaborado a partir de uva Tinta de Toro con una maduraci\u00f3n en barrica de tres meses que puedes comprar online y recibirlo en 48 horas en Paladar Plus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/","og_locale":"es_ES","og_type":"article","og_title":"Liberalia Vino Dos Tinto d.o. Toro para Comprar online","og_description":"Liberalia Vino Dos Tinto con denominaci\u00f3n de origen Vino de Toro es el m\u00e1s joven de Bodega Liberalia elaborado a partir de uva Tinta de Toro con una maduraci\u00f3n en barrica de tres meses que puedes comprar online y recibirlo en 48 horas en Paladar Plus","og_url":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/","og_site_name":"Paladar Plus","article_modified_time":"2023-07-01T19:41:08+00:00","og_image":[{"width":135,"height":528,"url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/liberalia_dos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/","url":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/","name":"Liberalia Vino Dos Tinto d.o. Toro para Comprar online","isPartOf":{"@id":"https:\/\/paladarplus.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/#primaryimage"},"image":{"@id":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/#primaryimage"},"thumbnailUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/liberalia_dos.jpg","datePublished":"2016-04-25T07:55:54+00:00","dateModified":"2023-07-01T19:41:08+00:00","description":"Liberalia Vino Dos Tinto con denominaci\u00f3n de origen Vino de Toro es el m\u00e1s joven de Bodega Liberalia elaborado a partir de uva Tinta de Toro con una maduraci\u00f3n en barrica de tres meses que puedes comprar online y recibirlo en 48 horas en Paladar Plus","breadcrumb":{"@id":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/#primaryimage","url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/liberalia_dos.jpg","contentUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/04\/liberalia_dos.jpg","width":135,"height":528,"caption":"Vino de Toro Liberalia Dos"},{"@type":"BreadcrumbList","@id":"https:\/\/paladarplus.es\/es\/vino-tinto-liberalia-dos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paladarplus.es\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/paladarplus.es\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Liberalia Vino Dos Tinto 2020"}]},{"@type":"WebSite","@id":"https:\/\/paladarplus.es\/es\/#website","url":"https:\/\/paladarplus.es\/es\/","name":"Paladar Plus","description":"Tienda de Vinos Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paladarplus.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product\/27391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/comments?post=27391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/media\/27385"}],"wp:attachment":[{"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/media?parent=27391"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product_brand?post=27391"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product_cat?post=27391"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/paladarplus.es\/es\/wp-json\/wp\/v2\/product_tag?post=27391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}