﻿{"id":135735,"date":"2016-08-10T07:42:30","date_gmt":"2016-08-10T05:42:30","guid":{"rendered":"https:\/\/paladarplus.es\/vino-tinto-tres-picos-borsao-garnacha-2018\/"},"modified":"2022-12-23T11:02:57","modified_gmt":"2022-12-23T09:02:57","slug":"vino-tinto-tres-picos-borsao-garnacha-2018","status":"publish","type":"product","link":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/","title":{"rendered":"Vino Tres Picos Borsao Garnacha 2018 Tinto"},"content":{"rendered":"<p><strong>Tres Picos Borsao 2018<\/strong>\u00a0es un vino acogido a la <strong>do Campo de Borja<\/strong> elaborado por <strong>Bodegas Borsao<\/strong> a partir de uva Garnacha con una crianza de 5 meses en barricas bordelesas de roble franc\u00e9s. Los vi\u00f1edos tienen una edad de entre 35 y 60 a\u00f1os plantados a una altitud de 600-700 metros.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/BHboK_U1l2U\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crianza de 5 meses en barricas de roble franc\u00e9s<\/p>\n","protected":false},"featured_media":29274,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17270,17271,14586,14587,14684,13984,13982],"product_tag":[11281,11284,11278],"class_list":["post-135735","product","type-product","status-publish","has-post-thumbnail","product_cat-bodegas-borsao-fr-2","product_cat-borsao-tinto-fr","product_cat-campo-de-borja-fr-2","product_cat-campo-de-borja-tintos-fr","product_cat-jovenes-fr","product_cat-vino-tinto-fr","product_cat-vinos-fr","product_tag-bodega-borsao-fr","product_tag-campo-de-borja-fr","product_tag-vino-tinto-tres-picos-borsao-garnacha-2016-fr","pa_denomination_of_origin-ec-campodeborja-fr","pa_formato_de_botella-2d-0_75litros-fr","pa_graduacion_alcoholica-0c-15degraduacionalcoholica-fr","pa_grape_variety-55-garnacha-fr","pa_manufacturer-a8-bodegasborsao-fr","pa_occasion-9f-aperitivos-fr","pa_occasion-97-barbacoa-fr","pa_occasion-89-celebraciones-fr","pa_occasion-69-cenainformal-fr","pa_occasion-21-cenaromantica-fr","pa_occasion-8e-comidaenfamilia-fr","pa_occasion-b8-compromiso-fr","pa_pairing-9f-aperitivos-fr","pa_pairing-42-arroces-fr","pa_pairing-2c-asados-fr","pa_pairing-11-carnesblancas-fr","pa_pairing-99-carnesrojas-fr","pa_pairing-0e-caza-fr","pa_pairing-50-embutidos-fr","pa_pairing-a9-guisos-fr","pa_pairing-36-quesos-fr","pa_style-58-roble-fr","pa_wine_type-99-tinto-fr","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vino Tres Picos Borsao Garnacha 2018 Tinto para comprar online<\/title>\n<meta name=\"description\" content=\"Vino Tres Picos Borsao Garnacha 2018 es un Tinto con denominaci\u00f3n de origen Campo de Borja de Garnacha y una crianza de 5 meses en barrica de roble, de color cereza y gran concentraci\u00f3n de aromas que puedes comprar online al mejor precio en Paladar Plus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vino Tres Picos Borsao Garnacha 2018 Tinto para comprar online\" \/>\n<meta property=\"og:description\" content=\"Vino Tres Picos Borsao Garnacha 2018 es un Tinto con denominaci\u00f3n de origen Campo de Borja de Garnacha y una crianza de 5 meses en barrica de roble, de color cereza y gran concentraci\u00f3n de aromas que puedes comprar online al mejor precio en Paladar Plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Paladar Plus\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-23T09:02:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/08\/tres_picos_borsao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"175\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/\",\"name\":\"Vino Tres Picos Borsao Garnacha 2018 Tinto para comprar online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/tres_picos_borsao.jpg\",\"datePublished\":\"2016-08-10T05:42:30+00:00\",\"dateModified\":\"2022-12-23T09:02:57+00:00\",\"description\":\"Vino Tres Picos Borsao Garnacha 2018 es un Tinto con denominaci\u00f3n de origen Campo de Borja de Garnacha y una crianza de 5 meses en barrica de roble, de color cereza y gran concentraci\u00f3n de aromas que puedes comprar online al mejor precio en Paladar Plus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/tres_picos_borsao.jpg\",\"contentUrl\":\"https:\\\/\\\/paladarplus.es\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/tres_picos_borsao.jpg\",\"width\":175,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/vino-tinto-tres-picos-borsao-garnacha-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vino Tres Picos Borsao Garnacha 2018 Tinto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/\",\"name\":\"Paladar Plus\",\"description\":\"Tienda de Vinos Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paladarplus.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vino Tres Picos Borsao Garnacha 2018 Tinto para comprar online","description":"Vino Tres Picos Borsao Garnacha 2018 es un Tinto con denominaci\u00f3n de origen Campo de Borja de Garnacha y una crianza de 5 meses en barrica de roble, de color cereza y gran concentraci\u00f3n de aromas que puedes comprar online al mejor precio en Paladar Plus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/","og_locale":"fr_FR","og_type":"article","og_title":"Vino Tres Picos Borsao Garnacha 2018 Tinto para comprar online","og_description":"Vino Tres Picos Borsao Garnacha 2018 es un Tinto con denominaci\u00f3n de origen Campo de Borja de Garnacha y una crianza de 5 meses en barrica de roble, de color cereza y gran concentraci\u00f3n de aromas que puedes comprar online al mejor precio en Paladar Plus","og_url":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/","og_site_name":"Paladar Plus","article_modified_time":"2022-12-23T09:02:57+00:00","og_image":[{"width":175,"height":595,"url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/08\/tres_picos_borsao.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/","url":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/","name":"Vino Tres Picos Borsao Garnacha 2018 Tinto para comprar online","isPartOf":{"@id":"https:\/\/paladarplus.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/#primaryimage"},"image":{"@id":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/08\/tres_picos_borsao.jpg","datePublished":"2016-08-10T05:42:30+00:00","dateModified":"2022-12-23T09:02:57+00:00","description":"Vino Tres Picos Borsao Garnacha 2018 es un Tinto con denominaci\u00f3n de origen Campo de Borja de Garnacha y una crianza de 5 meses en barrica de roble, de color cereza y gran concentraci\u00f3n de aromas que puedes comprar online al mejor precio en Paladar Plus","breadcrumb":{"@id":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/#primaryimage","url":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/08\/tres_picos_borsao.jpg","contentUrl":"https:\/\/paladarplus.es\/wp-content\/uploads\/2016\/08\/tres_picos_borsao.jpg","width":175,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/paladarplus.es\/fr\/vino-tinto-tres-picos-borsao-garnacha-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paladarplus.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/paladarplus.es\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Vino Tres Picos Borsao Garnacha 2018 Tinto"}]},{"@type":"WebSite","@id":"https:\/\/paladarplus.es\/es\/#website","url":"https:\/\/paladarplus.es\/es\/","name":"Paladar Plus","description":"Tienda de Vinos Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paladarplus.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/product\/135735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/comments?post=135735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/media\/29274"}],"wp:attachment":[{"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/media?parent=135735"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/product_brand?post=135735"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/product_cat?post=135735"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/paladarplus.es\/fr\/wp-json\/wp\/v2\/product_tag?post=135735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}